{"id":408,"date":"2016-01-07T09:31:53","date_gmt":"2016-01-07T09:31:53","guid":{"rendered":"http:\/\/consulting.stylemixthemes.com\/?page_id=408"},"modified":"2026-04-15T04:06:34","modified_gmt":"2026-04-15T04:06:34","slug":"careers","status":"publish","type":"page","link":"https:\/\/muzalpharma.com\/vc\/index.php\/company-overview\/careers\/","title":{"rendered":"Misi\u00f3n y Visi\u00f3n"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"408\" class=\"elementor elementor-408\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7fab6496 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7fab6496\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6da23b54\" data-id=\"6da23b54\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4a565f7e elementor-widget__width-inherit elementor-widget elementor-widget-text-editor\" data-id=\"4a565f7e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>[vc_row css=&#8221;.vc_custom_1459506339266{margin-bottom: 100px !important;}&#8221;][vc_column offset=&#8221;vc_col-lg-9 vc_col-md-9&#8243;][vc_column_text css=&#8221;.vc_custom_1643944887765{margin-bottom: 52px !important;}&#8221;]<\/p>\n<h2>MISION<\/h2>\n<p>MUZALPHARMA S.A, es una sociedad an\u00f3nima legalmente constituida, dedicada a brindar soluciones integrales de material de empaque, para apoyar la producci\u00f3n de la industria farmac\u00e9utica, veterinaria, de productos naturales, etc., con enfoque en la satisfacci\u00f3n de las necesidades de nuestros clientes, mediante el soporte y respaldo de proveedores aliados de clase mundial y estrategias de negocios, impulsando el desarrollo de la industria a nivel nacional.[\/vc_column_text][vc_column_text css=&#8221;.vc_custom_1643944898330{margin-bottom: 52px !important;}&#8221;]<\/p>\n<h2>VISION<\/h2>\n<p>Ser una empresa l\u00edder y referente en el sector industrial ecuatoriano, reconocida por proveer soluciones integrales y altamente calificadas en materiales de empaque. Ofrecemos una s\u00f3lida fuerza de negociaci\u00f3n y una asesor\u00eda de car\u00e1cter contempor\u00e1neo, en sinton\u00eda con los desaf\u00edos y las din\u00e1micas del mercado nacional.<\/p>\n<p>[\/vc_column_text][vc_row_inner css=&#8221;.vc_custom_1453463400247{margin-bottom: 30px !important;}&#8221;][vc_column_inner width=&#8221;1\/2&#8243;][vc_single_image image=&#8221;7787&#8243; img_size=&#8221;500X500&#8243;][\/vc_column_inner][vc_column_inner width=&#8221;1\/2&#8243;][stm_spacing lg_spacing=&#8221;0&#8243; md_spacing=&#8221;0&#8243; sm_spacing=&#8221;0&#8243; xs_spacing=&#8221;30&#8243;][vc_custom_heading text=&#8221;Beneficios&#8221; font_container=&#8221;tag:h4|text_align:left|color:%23222222&#8243; use_theme_fonts=&#8221;yes&#8221; css=&#8221;.vc_custom_1643424887036{margin-bottom: 15px !important;}&#8221; el_class=&#8221;no_stripe remove_padding&#8221;][vc_column_text]Cuidamos el negocio de nuestros clientes como nuestro negocio. Pensamos y actuamos como socios comerciales. Compartimos las aspiraciones de nuestros clientes, trabajamos para comprender su realidad y alineamos nuestros incentivos con sus objetivos, para que sepan que estamos juntos en esto.<\/p>\n<p>El impacto personal, la asesoria y el trabajo en equipo son solo algunos de los beneficios de construir nuestros productos[\/vc_column_text][\/vc_column_inner][\/vc_row_inner][\/vc_column][vc_column offset=&#8221;vc_col-lg-3 vc_col-md-3&#8243;][stm_sidebar sidebar=&#8221;1471&#8243;][\/vc_column][\/vc_row]<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>[vc_row css=&#8221;.vc_custom_1459506339266{margin-bottom: 100px !important;}&#8221;][vc_column offset=&#8221;vc_col-lg-9 vc_col-md-9&#8243;][vc_column_text css=&#8221;.vc_custom_1643944887765{margin-bottom: 52px !important;}&#8221;] MISION MUZALPHARMA S.A, es una sociedad an\u00f3nima legalmente constituida, dedicada a brindar soluciones integrales de material de empaque, para apoyar la producci\u00f3n de la industria farmac\u00e9utica, veterinaria, de productos naturales, etc., con enfoque en la satisfacci\u00f3n de las necesidades de nuestros clientes, mediante el soporte y<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4735,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_canvas","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"class_list":["post-408","page","type-page","status-publish","hentry"],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/muzalpharma.com\/vc\/index.php\/wp-json\/wp\/v2\/pages\/408","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/muzalpharma.com\/vc\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/muzalpharma.com\/vc\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/muzalpharma.com\/vc\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/muzalpharma.com\/vc\/index.php\/wp-json\/wp\/v2\/comments?post=408"}],"version-history":[{"count":19,"href":"https:\/\/muzalpharma.com\/vc\/index.php\/wp-json\/wp\/v2\/pages\/408\/revisions"}],"predecessor-version":[{"id":9807,"href":"https:\/\/muzalpharma.com\/vc\/index.php\/wp-json\/wp\/v2\/pages\/408\/revisions\/9807"}],"up":[{"embeddable":true,"href":"https:\/\/muzalpharma.com\/vc\/index.php\/wp-json\/wp\/v2\/pages\/4735"}],"wp:attachment":[{"href":"https:\/\/muzalpharma.com\/vc\/index.php\/wp-json\/wp\/v2\/media?parent=408"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}